{"id":4054,"date":"2013-10-31T15:14:54","date_gmt":"2013-10-31T15:14:54","guid":{"rendered":"http:\/\/mfwa.africafex.org\/?p=4054"},"modified":"2015-11-27T15:15:49","modified_gmt":"2015-11-27T15:15:49","slug":"mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution","status":"publish","type":"post","link":"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/","title":{"rendered":"MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution"},"content":{"rendered":"<p style=\"text-align: justify;\">Le directeur de r\u00e9daction et le r\u00e9dacteur en chef du journal priv\u00e9e <em>l\u2019Independent Observer<\/em> Jonathan Leigh et Bai Bai Sesay avaient, de\u00a0 nouveau \u00e9t\u00e9 refus\u00e9 la libert\u00e9 provisoire, le 29 Octobre 2013,\u00a0 par un tribunal de premi\u00e8re instance bas\u00e9e \u00e0 Freetown.<\/p>\n<p style=\"text-align: justify;\">\u00a0Les deux journalistes qui ont \u00e9t\u00e9 inculp\u00e9 de\u00a0 26 chefs d&#8217;accusation de diffamation s\u00e9ditieuse et diffamatoire, ont pass\u00e9 13 jours en d\u00e9tention depuis leur arrestation le 18 octobre, pour avoir publi\u00e9 un article jug\u00e9 diffamatoire au Pr\u00e9sident sierra-l\u00e9onais, Ernest Bai Koroma. Le proc\u00e8s a \u00e9t\u00e9 ajourn\u00e9 au 4 novembre.<\/p>\n<p>En attendant, la Sierra Leone Journalists Association (SLAJ), ont entam\u00e9 le 29 octobre un black-out m\u00e9diatique dont l\u2019objet \u00e9tait de protester contre la d\u00e9tention continue de Leigh et Sesay.<\/p>\n<p>Selon le pr\u00e9sident de la\u00a0 SLAJ, Kelvin Lewis, sur les quelques 40 journaux publi\u00e9s chaque jour,\u00a0 seulement deux avaient \u00e9t\u00e9 publi\u00e9s ce jour-l\u00e0\u00a0; il s\u2019agissait des journaux. <em>Awareness\u00a0 Times<\/em> \u00e9dit\u00e9 par l&#8217;adjoint sp\u00e9cial ex\u00e9cutif du Pr\u00e9sident Koroma, le Dr Sylvia Blyden et le <em>Standard Times<\/em> publi\u00e9 par un nomm\u00e9 Philip Neville.<\/p>\n<p>Aussi, sur une soixantaine des stations radio qui se trouvent \u00e0 travers tout le pays, seul la Sierre Leone Broadcasting corporation (SLBC), l\u2019audiovisuel d&#8217;Etat ainsi que <em>Star Radio<\/em>, qui appartient \u00e9galement \u00e0 Neville, n&#8217;ont pas pris part au le black-out.<\/p>\n<p>Lewis a \u00e9galement confi\u00e9 \u00e0 la MFWA que si les journalistes ne retrouvent pas leur libert\u00e9, les m\u00e9dias boycotteront toutes les fonctions du gouvernement et refuseront de mettre leur espace, dans leurs journaux et sur leurs antennes, \u00e0 la disposition de l\u2019\u00e9tat.<\/p>\n<p>La MFWA d\u00e9nonce\u00a0 la d\u00e9tention continue de Leigh et Sesay et invite le Pr\u00e9sident Koroma de faire manifester\u00a0 son attachement \u00e0 la libert\u00e9 de la presse en autorisant la lib\u00e9ration des journalistes.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Le directeur de r\u00e9daction et le r\u00e9dacteur en chef du journal priv\u00e9e l\u2019Independent Observer Jonathan Leigh et Bai&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[254],"tags":[],"country":[252],"staff-position":[],"opportunity-category":[],"ppma_author":[513],"class_list":["post-4054","post","type-post","status-publish","format-standard","hentry","category-free-expression-violations-fr","country-sierra-leone-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution - Media Foundation For West Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution - Media Foundation For West Africa\" \/>\n<meta property=\"og:description\" content=\"Le directeur de r\u00e9daction et le r\u00e9dacteur en chef du journal priv\u00e9e l\u2019Independent Observer Jonathan Leigh et Bai&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/\" \/>\n<meta property=\"og:site_name\" content=\"Media Foundation For West Africa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/themfwa\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-31T15:14:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-27T15:15:49+00:00\" \/>\n<meta name=\"author\" content=\"Vivian Affoah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:site\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vivian Affoah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\\\/\"},\"author\":{\"name\":\"Vivian Affoah\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/person\\\/6a1a8151b41fab6317c9544da609a96b\"},\"headline\":\"MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution\",\"datePublished\":\"2013-10-31T15:14:54+00:00\",\"dateModified\":\"2015-11-27T15:15:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\\\/\"},\"wordCount\":319,\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"articleSection\":[\"Les violations de la libre expression\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\\\/\",\"name\":\"MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution - Media Foundation For West Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\"},\"datePublished\":\"2013-10-31T15:14:54+00:00\",\"dateModified\":\"2015-11-27T15:15:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"name\":\"Media Foundation For West Africa\",\"description\":\"Promoting Freedom of Expression and Democracy in West Africa\",\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\",\"name\":\"Media Foundation for West Africa\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"width\":1683,\"height\":1113,\"caption\":\"Media Foundation for West Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/themfwa\",\"https:\\\/\\\/x.com\\\/TheMFWA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCF6HrPuXcV1K1Ed8AAq4Rdw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/person\\\/6a1a8151b41fab6317c9544da609a96b\",\"name\":\"Vivian Affoah\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g719420b9d28a4a0781c1038ec6921926\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g\",\"caption\":\"Vivian Affoah\"},\"sameAs\":[\"http:\\\/\\\/www.mfwa.org\"],\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/author\\\/vivian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution - Media Foundation For West Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/","og_locale":"fr_FR","og_type":"article","og_title":"MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution - Media Foundation For West Africa","og_description":"Le directeur de r\u00e9daction et le r\u00e9dacteur en chef du journal priv\u00e9e l\u2019Independent Observer Jonathan Leigh et Bai&hellip;","og_url":"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/","og_site_name":"Media Foundation For West Africa","article_publisher":"https:\/\/www.facebook.com\/themfwa","article_published_time":"2013-10-31T15:14:54+00:00","article_modified_time":"2015-11-27T15:15:49+00:00","author":"Vivian Affoah","twitter_card":"summary_large_image","twitter_creator":"@TheMFWA","twitter_site":"@TheMFWA","twitter_misc":{"Written by":"Vivian Affoah","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/#article","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/"},"author":{"name":"Vivian Affoah","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/person\/6a1a8151b41fab6317c9544da609a96b"},"headline":"MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution","datePublished":"2013-10-31T15:14:54+00:00","dateModified":"2015-11-27T15:15:49+00:00","mainEntityOfPage":{"@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/"},"wordCount":319,"publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"articleSection":["Les violations de la libre expression"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/","url":"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/","name":"MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution - Media Foundation For West Africa","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/#website"},"datePublished":"2013-10-31T15:14:54+00:00","dateModified":"2015-11-27T15:15:49+00:00","breadcrumb":{"@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-sierra-leone-tribunal-refuse-de-nouveau-de-liberer-les-journalistes-detenus-sous-caution\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mfwa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"MISE \u00c0 JOUR\u00a0 Sierra Leone: Tribunal refuse de nouveau de lib\u00e9rer les Journalistes d\u00e9tenus sous caution"}]},{"@type":"WebSite","@id":"https:\/\/mfwa.org\/fr\/#website","url":"https:\/\/mfwa.org\/fr\/","name":"Media Foundation For West Africa","description":"Promoting Freedom of Expression and Democracy in West Africa","publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mfwa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mfwa.org\/fr\/#organization","name":"Media Foundation for West Africa","url":"https:\/\/mfwa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","width":1683,"height":1113,"caption":"Media Foundation for West Africa"},"image":{"@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/themfwa","https:\/\/x.com\/TheMFWA","https:\/\/www.youtube.com\/channel\/UCF6HrPuXcV1K1Ed8AAq4Rdw"]},{"@type":"Person","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/person\/6a1a8151b41fab6317c9544da609a96b","name":"Vivian Affoah","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g719420b9d28a4a0781c1038ec6921926","url":"https:\/\/secure.gravatar.com\/avatar\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g","caption":"Vivian Affoah"},"sameAs":["http:\/\/www.mfwa.org"],"url":"https:\/\/mfwa.org\/fr\/author\/vivian\/"}]}},"authors":[{"term_id":513,"user_id":2,"is_guest":0,"slug":"vivian","display_name":"Vivian Affoah","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/posts\/4054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/comments?post=4054"}],"version-history":[{"count":0,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/posts\/4054\/revisions"}],"wp:attachment":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media?parent=4054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/categories?post=4054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/tags?post=4054"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/country?post=4054"},{"taxonomy":"staff-position","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/staff-position?post=4054"},{"taxonomy":"opportunity-category","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/opportunity-category?post=4054"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/ppma_author?post=4054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}