{"id":12313,"date":"2018-03-14T14:33:00","date_gmt":"2018-03-14T14:33:00","guid":{"rendered":"http:\/\/www.mfwa.org\/?p=12313"},"modified":"2018-03-26T14:52:20","modified_gmt":"2018-03-26T14:52:20","slug":"mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes","status":"publish","type":"post","link":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/","title":{"rendered":"MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes"},"content":{"rendered":"<p style=\"text-align: justify;\">La Fondation des M\u00e9dias pour l\u2019Afrique de l\u2019Ouest (MFWA) a p\u00e9titionn\u00e9 l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les assassinats de quatre journalistes dans des incidents s\u00e9par\u00e9s qui ont lieu dans le pays en 2017.<\/p>\n<p style=\"text-align: justify;\">Quatre journalistes Nig\u00e9rian ont \u00e9t\u00e9 tu\u00e9s par balles par des inconnus arm\u00e9s au cours de l\u2019ann\u00e9e pass\u00e9e. Il s\u2019agit des journalistes Famous Giobaro (Etat de Bayelsa), Lawrence Okojie (Etat d\u2019Edo), Ikechukwu Onubogu (Etat d\u2019Anambra) et Abdul Ganiy Lawal (Etat d\u2019Ekiti).<\/p>\n<p style=\"text-align: justify;\">La p\u00e9tition qui date du 8 Mars 2018, a \u00e9t\u00e9 envoy\u00e9e par courrier postal et e-mail, et demande \u00e0 l\u2019IGP Ibrahim Kpotun Idris de s\u2019assurer de l\u2019arrestation et de la pr\u00e9sentation devant la justice les auteurs de ces assassinats, \u00e9tant donn\u00e9 que l\u2019impunit\u00e9\u00a0 de ces crimes a le potentiel semer la peur et induire l\u2019autocensure parmi les journalistes au Nigeria.<\/p>\n<p style=\"text-align: justify;\">La MFWA estime qu\u2019\u00e9tant donn\u00e9 que ces assassinats ont le potentiel de causer la panique au sein des journalistes, c\u2019est important que les motifs de ces assassinats soient \u00e9tablis.<\/p>\n<p style=\"text-align: justify;\">\u00ab Si les motifs de ces meurtres ne sont pas connus, seul des investigations effectives peuvent \u00e9tablir si les victimes ont \u00e9t\u00e9 tu\u00e9es du fait de leurs professions ou non, d\u2019o\u00f9 la n\u00e9cessit\u00e9 de d\u00e9nouer les mobiles de ces assassinats, a dit la MFWA.<\/p>\n<p style=\"text-align: justify;\">La MFWA exhorte l\u2019IGP \u00e0 intensifier les investigations sur ces assistanats et informer la population du Nigeria et la fraternit\u00e9 des m\u00e9dias en Afrique de l\u2019Ouest \u00e0 propos de ces affaires d\u2019ici la fin du premier trimestre de cette ann\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Lire <a href=\"http:\/\/www.mfwa.org\/wp-content\/uploads\/2018\/03\/Petition-to-Nigeria-IGP-Ibrahim-Kpotun-Idris-1.pdf\">la comp\u00e9tition enti\u00e8re ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fondation des M\u00e9dias pour l\u2019Afrique de l\u2019Ouest (MFWA) a p\u00e9titionn\u00e9 l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria<\/p>\n","protected":false},"author":2,"featured_media":12278,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,230],"tags":[],"country":[250],"staff-position":[],"opportunity-category":[],"ppma_author":[513],"class_list":["post-12313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","category-impunity-fr","country-nigeria-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes - Media Foundation For West Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes - Media Foundation For West Africa\" \/>\n<meta property=\"og:description\" content=\"La Fondation des M\u00e9dias pour l\u2019Afrique de l\u2019Ouest (MFWA) a p\u00e9titionn\u00e9 l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/\" \/>\n<meta property=\"og:site_name\" content=\"Media Foundation For West Africa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/themfwa\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-14T14:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-26T14:52:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mfwa.org\/wp-content\/uploads\/2018\/03\/naija-IGP-and-president.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vivian Affoah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:site\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vivian Affoah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/\"},\"author\":{\"name\":\"Vivian Affoah\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/person\\\/6a1a8151b41fab6317c9544da609a96b\"},\"headline\":\"MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes\",\"datePublished\":\"2018-03-14T14:33:00+00:00\",\"dateModified\":\"2018-03-26T14:52:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/\"},\"wordCount\":306,\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/naija-IGP-and-president.jpg\",\"articleSection\":[\".\",\"Impunit\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/\",\"name\":\"MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes - Media Foundation For West Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/naija-IGP-and-president.jpg\",\"datePublished\":\"2018-03-14T14:33:00+00:00\",\"dateModified\":\"2018-03-26T14:52:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/naija-IGP-and-president.jpg\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/naija-IGP-and-president.jpg\",\"width\":800,\"height\":451},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"name\":\"Media Foundation For West Africa\",\"description\":\"Promoting Freedom of Expression and Democracy in West Africa\",\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\",\"name\":\"Media Foundation for West Africa\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"width\":1683,\"height\":1113,\"caption\":\"Media Foundation for West Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/themfwa\",\"https:\\\/\\\/x.com\\\/TheMFWA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCF6HrPuXcV1K1Ed8AAq4Rdw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/person\\\/6a1a8151b41fab6317c9544da609a96b\",\"name\":\"Vivian Affoah\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g719420b9d28a4a0781c1038ec6921926\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g\",\"caption\":\"Vivian Affoah\"},\"sameAs\":[\"http:\\\/\\\/www.mfwa.org\"],\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/author\\\/vivian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes - Media Foundation For West Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/","og_locale":"fr_FR","og_type":"article","og_title":"MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes - Media Foundation For West Africa","og_description":"La Fondation des M\u00e9dias pour l\u2019Afrique de l\u2019Ouest (MFWA) a p\u00e9titionn\u00e9 l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria","og_url":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/","og_site_name":"Media Foundation For West Africa","article_publisher":"https:\/\/www.facebook.com\/themfwa","article_published_time":"2018-03-14T14:33:00+00:00","article_modified_time":"2018-03-26T14:52:20+00:00","og_image":[{"width":800,"height":451,"url":"https:\/\/mfwa.org\/wp-content\/uploads\/2018\/03\/naija-IGP-and-president.jpg","type":"image\/jpeg"}],"author":"Vivian Affoah","twitter_card":"summary_large_image","twitter_creator":"@TheMFWA","twitter_site":"@TheMFWA","twitter_misc":{"Written by":"Vivian Affoah","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/#article","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/"},"author":{"name":"Vivian Affoah","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/person\/6a1a8151b41fab6317c9544da609a96b"},"headline":"MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes","datePublished":"2018-03-14T14:33:00+00:00","dateModified":"2018-03-26T14:52:20+00:00","mainEntityOfPage":{"@id":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/"},"wordCount":306,"publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"image":{"@id":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/#primaryimage"},"thumbnailUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2018\/03\/naija-IGP-and-president.jpg","articleSection":[".","Impunit\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/","url":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/","name":"MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes - Media Foundation For West Africa","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/#primaryimage"},"image":{"@id":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/#primaryimage"},"thumbnailUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2018\/03\/naija-IGP-and-president.jpg","datePublished":"2018-03-14T14:33:00+00:00","dateModified":"2018-03-26T14:52:20+00:00","breadcrumb":{"@id":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/#primaryimage","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2018\/03\/naija-IGP-and-president.jpg","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2018\/03\/naija-IGP-and-president.jpg","width":800,"height":451},{"@type":"BreadcrumbList","@id":"https:\/\/mfwa.org\/fr\/mfwa-petitionne-linspecteur-general-de-la-police-du-nigeria-sur-les-meurtres-de-quatre-journalistes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mfwa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"MFWA P\u00e9titionne l\u2019Inspecteur G\u00e9n\u00e9ral de la Police du Nigeria sur les Meurtres de Quatre Journalistes"}]},{"@type":"WebSite","@id":"https:\/\/mfwa.org\/fr\/#website","url":"https:\/\/mfwa.org\/fr\/","name":"Media Foundation For West Africa","description":"Promoting Freedom of Expression and Democracy in West Africa","publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mfwa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mfwa.org\/fr\/#organization","name":"Media Foundation for West Africa","url":"https:\/\/mfwa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","width":1683,"height":1113,"caption":"Media Foundation for West Africa"},"image":{"@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/themfwa","https:\/\/x.com\/TheMFWA","https:\/\/www.youtube.com\/channel\/UCF6HrPuXcV1K1Ed8AAq4Rdw"]},{"@type":"Person","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/person\/6a1a8151b41fab6317c9544da609a96b","name":"Vivian Affoah","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g719420b9d28a4a0781c1038ec6921926","url":"https:\/\/secure.gravatar.com\/avatar\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g","caption":"Vivian Affoah"},"sameAs":["http:\/\/www.mfwa.org"],"url":"https:\/\/mfwa.org\/fr\/author\/vivian\/"}]}},"authors":[{"term_id":513,"user_id":2,"is_guest":0,"slug":"vivian","display_name":"Vivian Affoah","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/ddf6c5c2ef2f35c978196ce314f9b81dba2ec548b12806a3acbe02e2360d7e63?s=96&d=mm&r=g","author_category":"","first_name":"Vivian","last_name":"Affoah","user_url":"http:\/\/www.mfwa.org","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/posts\/12313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/comments?post=12313"}],"version-history":[{"count":0,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/posts\/12313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media\/12278"}],"wp:attachment":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media?parent=12313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/categories?post=12313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/tags?post=12313"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/country?post=12313"},{"taxonomy":"staff-position","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/staff-position?post=12313"},{"taxonomy":"opportunity-category","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/opportunity-category?post=12313"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/ppma_author?post=12313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}