{"id":11179,"date":"2017-09-13T15:38:27","date_gmt":"2017-09-13T15:38:27","guid":{"rendered":"http:\/\/www.mfwa.org\/?p=11179"},"modified":"2017-09-14T11:32:47","modified_gmt":"2017-09-14T11:32:47","slug":"mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure","status":"publish","type":"post","link":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/","title":{"rendered":"Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure"},"content":{"rendered":"<p>Les autorit\u00e9s togolaises ont restaur\u00e9 l\u2019internet dans le pays apr\u00e8s cinq jours de coupure lors des r\u00e9centes manifestations organis\u00e9es par une coalition de partis politiques pour r\u00e9clamer les r\u00e9formes politiques.<u><\/u><u><\/u><\/p>\n<p>WhatsApp, Facebook et autres services d\u2019internet ont \u00e9t\u00e9 restaur\u00e9s le 10 Septembre 2017, apr\u00e8s que l\u2019acc\u00e8s \u00e0 l\u2019internet ait \u00e9t\u00e9\u00a0<a href=\"http:\/\/www.mfwa.org\/opposition-demonstration-eclipsed-by-social-media-blackout\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=en&amp;q=http:\/\/www.mfwa.org\/opposition-demonstration-eclipsed-by-social-media-blackout\/&amp;source=gmail&amp;ust=1505473548266000&amp;usg=AFQjCNGPSIZL7ZDRmjTx7YHLTvj4FijBrA\">coup\u00e9<\/a>\u00a0le 5 Septembre, \u00e0 la veille des manifestations gigantesque qu\u2019a connu le pays. La coupure a dur\u00e9 cinq jours.<u><\/u><u><\/u><\/p>\n<p>La coupure a g\u00e9n\u00e9r\u00e9 une vaste condamnation et des appels des organisations de la libert\u00e9 d\u2019expression, de la libert\u00e9 de la presse et des droits d\u2019internet au Togo et du monde, y compris la Fondation des M\u00e9dias pour l\u2019Afrique de l\u2019Ouest(MFWA).<u><\/u><u><\/u><\/p>\n<p>Le Togo a \u00e9t\u00e9 le th\u00e9\u00e2tre des tensions politiques alors que la coalition des partis d\u2019opposition politiques et leurs sympathisants multipliaient la pression sur le gouvernement. Ils r\u00e9clamaient des\u00a0 reformes politiques, y compris la limitation des mandats pr\u00e9sidentiels.<u><\/u><u><\/u><\/p>\n<p>Dans leurs tentatives de taire les voix dissidents de l\u2019opposition, les autorit\u00e9s ont coup\u00e9 l\u2019acc\u00e8s aux r\u00e9seaux sociaux et emp\u00each\u00e9 les m\u00e9dias critiques de couvrir les manifestations.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les autorit\u00e9s togolaises ont restaur\u00e9 l\u2019internet dans le pays apr\u00e8s cinq jours de coupure lors des r\u00e9centes manifestations<\/p>\n","protected":false},"author":1,"featured_media":11169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,169,254],"tags":[],"country":[253],"staff-position":[],"opportunity-category":[],"ppma_author":[516],"class_list":["post-11179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","category-digital-rights","category-free-expression-violations-fr","country-togo-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure - Media Foundation For West Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure - Media Foundation For West Africa\" \/>\n<meta property=\"og:description\" content=\"Les autorit\u00e9s togolaises ont restaur\u00e9 l\u2019internet dans le pays apr\u00e8s cinq jours de coupure lors des r\u00e9centes manifestations\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/\" \/>\n<meta property=\"og:site_name\" content=\"Media Foundation For West Africa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/themfwa\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-13T15:38:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-14T11:32:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/09\/Faure-Gnassingbe-1-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"721\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mesh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:site\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mesh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/\"},\"author\":{\"name\":\"mesh\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/person\\\/60f6ba95dbcbbd60ff9a2c18c6f02dd7\"},\"headline\":\"Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure\",\"datePublished\":\"2017-09-13T15:38:27+00:00\",\"dateModified\":\"2017-09-14T11:32:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/\"},\"wordCount\":218,\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Faure-Gnassingbe-1-.jpg\",\"articleSection\":[\".\",\"Digital Rights\",\"Les violations de la libre expression\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/\",\"name\":\"Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure - Media Foundation For West Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Faure-Gnassingbe-1-.jpg\",\"datePublished\":\"2017-09-13T15:38:27+00:00\",\"dateModified\":\"2017-09-14T11:32:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Faure-Gnassingbe-1-.jpg\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Faure-Gnassingbe-1-.jpg\",\"width\":721,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"name\":\"Media Foundation For West Africa\",\"description\":\"Promoting Freedom of Expression and Democracy in West Africa\",\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\",\"name\":\"Media Foundation for West Africa\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"width\":1683,\"height\":1113,\"caption\":\"Media Foundation for West Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/themfwa\",\"https:\\\/\\\/x.com\\\/TheMFWA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCF6HrPuXcV1K1Ed8AAq4Rdw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/person\\\/60f6ba95dbcbbd60ff9a2c18c6f02dd7\",\"name\":\"mesh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63efdf1bdd5192677168cb7e6124d514459f8c2e269a54eb912e96de64276547?s=96&d=mm&r=gd03458ced96c975369b9ecc652438752\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63efdf1bdd5192677168cb7e6124d514459f8c2e269a54eb912e96de64276547?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63efdf1bdd5192677168cb7e6124d514459f8c2e269a54eb912e96de64276547?s=96&d=mm&r=g\",\"caption\":\"mesh\"},\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/author\\\/mesh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure - Media Foundation For West Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/","og_locale":"fr_FR","og_type":"article","og_title":"Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure - Media Foundation For West Africa","og_description":"Les autorit\u00e9s togolaises ont restaur\u00e9 l\u2019internet dans le pays apr\u00e8s cinq jours de coupure lors des r\u00e9centes manifestations","og_url":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/","og_site_name":"Media Foundation For West Africa","article_publisher":"https:\/\/www.facebook.com\/themfwa","article_published_time":"2017-09-13T15:38:27+00:00","article_modified_time":"2017-09-14T11:32:47+00:00","og_image":[{"width":721,"height":406,"url":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/09\/Faure-Gnassingbe-1-.jpg","type":"image\/jpeg"}],"author":"mesh","twitter_card":"summary_large_image","twitter_creator":"@TheMFWA","twitter_site":"@TheMFWA","twitter_misc":{"Written by":"mesh","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/#article","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/"},"author":{"name":"mesh","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/person\/60f6ba95dbcbbd60ff9a2c18c6f02dd7"},"headline":"Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure","datePublished":"2017-09-13T15:38:27+00:00","dateModified":"2017-09-14T11:32:47+00:00","mainEntityOfPage":{"@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/"},"wordCount":218,"publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"image":{"@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/#primaryimage"},"thumbnailUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/09\/Faure-Gnassingbe-1-.jpg","articleSection":[".","Digital Rights","Les violations de la libre expression"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/","url":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/","name":"Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure - Media Foundation For West Africa","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/#primaryimage"},"image":{"@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/#primaryimage"},"thumbnailUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/09\/Faure-Gnassingbe-1-.jpg","datePublished":"2017-09-13T15:38:27+00:00","dateModified":"2017-09-14T11:32:47+00:00","breadcrumb":{"@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/#primaryimage","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/09\/Faure-Gnassingbe-1-.jpg","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/09\/Faure-Gnassingbe-1-.jpg","width":721,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/mfwa.org\/fr\/mise-a-jour-restauration-de-linternet-au-togo-apres-cinq-jour-de-coupure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mfwa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Mise \u00e0 Jour: Restauration de l\u2019Internet au Togo apr\u00e8s Cinq Jour de Coupure"}]},{"@type":"WebSite","@id":"https:\/\/mfwa.org\/fr\/#website","url":"https:\/\/mfwa.org\/fr\/","name":"Media Foundation For West Africa","description":"Promoting Freedom of Expression and Democracy in West Africa","publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mfwa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mfwa.org\/fr\/#organization","name":"Media Foundation for West Africa","url":"https:\/\/mfwa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","width":1683,"height":1113,"caption":"Media Foundation for West Africa"},"image":{"@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/themfwa","https:\/\/x.com\/TheMFWA","https:\/\/www.youtube.com\/channel\/UCF6HrPuXcV1K1Ed8AAq4Rdw"]},{"@type":"Person","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/person\/60f6ba95dbcbbd60ff9a2c18c6f02dd7","name":"mesh","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/63efdf1bdd5192677168cb7e6124d514459f8c2e269a54eb912e96de64276547?s=96&d=mm&r=gd03458ced96c975369b9ecc652438752","url":"https:\/\/secure.gravatar.com\/avatar\/63efdf1bdd5192677168cb7e6124d514459f8c2e269a54eb912e96de64276547?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63efdf1bdd5192677168cb7e6124d514459f8c2e269a54eb912e96de64276547?s=96&d=mm&r=g","caption":"mesh"},"url":"https:\/\/mfwa.org\/fr\/author\/mesh\/"}]}},"authors":[{"term_id":516,"user_id":1,"is_guest":0,"slug":"mesh","display_name":"mesh","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/63efdf1bdd5192677168cb7e6124d514459f8c2e269a54eb912e96de64276547?s=96&d=mm&r=g","author_category":"","first_name":"","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/posts\/11179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/comments?post=11179"}],"version-history":[{"count":0,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/posts\/11179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media\/11169"}],"wp:attachment":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media?parent=11179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/categories?post=11179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/tags?post=11179"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/country?post=11179"},{"taxonomy":"staff-position","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/staff-position?post=11179"},{"taxonomy":"opportunity-category","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/opportunity-category?post=11179"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/ppma_author?post=11179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}