{"id":5693,"date":"2016-02-08T14:23:45","date_gmt":"2016-02-08T14:23:45","guid":{"rendered":"http:\/\/www.mfwa.org\/?post_type=our-partners-list&#038;p=5693"},"modified":"2016-02-12T17:57:37","modified_gmt":"2016-02-12T17:57:37","slug":"mauritania-regroupement-de-la-presse-mauritanienne-rpm","status":"publish","type":"our-partners-list","link":"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/","title":{"rendered":"Regroupement de la Presse Mauritanienne (RPM)"},"content":{"rendered":"<p style=\"text-align: justify;\">RPM est une association mauritanienne des professionnels des m\u00e9dias \u00a0qui a \u00e9t\u00e9 \u00a0cr\u00e9\u00e9e en 2005. Elle est compos\u00e9e actuellement de 32 organisations des m\u00e9dias allant des journaux, la \u00a0T\u00e9l\u00e9vision, la radio et de la presse en ligne. Les objectifs de RPM sont la cr\u00e9ation d\u2019un cadre pour promouvoir et \u00e9tendre le rayonnement de la Libert\u00e9 d\u2019Expression (FoE) dans l\u2019\u00e9dification de la d\u00e9mocratie, et l\u2019am\u00e9lioration des capacit\u00e9s des professionnels des m\u00e9dias et du pluralisme journalistique. Elle organise un d\u00e9bat annuel qui rassemble les leaders qui dirigent le gouvernement et ceux de la classe d\u2019opposition. Aussi, elle organise \u00a0les d\u00e9bats sur des probl\u00e8mes du pluralisme m\u00e9diatique et le r\u00f4le des m\u00e9dia en ligne. Le RPM joue le r\u00f4le du\u00a0 chien de garde pour la Libert\u00e9 d\u2019Expression (FoE) et publie des alertes sur les violations de la libert\u00e9 de parole et la suret\u00e9 des journalistes.<\/p>\n","protected":false},"featured_media":5689,"template":"","partner-type":[302],"class_list":["post-5693","our-partners-list","type-our-partners-list","status-publish","has-post-thumbnail","hentry","partner-type-partenaires-nationaux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regroupement de la Presse Mauritanienne (RPM) - Media Foundation For West Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regroupement de la Presse Mauritanienne (RPM) - Media Foundation For West Africa\" \/>\n<meta property=\"og:description\" content=\"RPM est une association mauritanienne des professionnels des m\u00e9dias \u00a0qui a \u00e9t\u00e9 \u00a0cr\u00e9\u00e9e en 2005. Elle est compos\u00e9e&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/\" \/>\n<meta property=\"og:site_name\" content=\"Media Foundation For West Africa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/themfwa\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-12T17:57:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mfwa.org\/wp-content\/uploads\/2016\/02\/RPM_logo_arabic_fr_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\\\/\",\"name\":\"Regroupement de la Presse Mauritanienne (RPM) - Media Foundation For West Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/RPM_logo_arabic_fr_1.jpg\",\"datePublished\":\"2016-02-08T14:23:45+00:00\",\"dateModified\":\"2016-02-12T17:57:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/RPM_logo_arabic_fr_1.jpg\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/RPM_logo_arabic_fr_1.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our Partners\",\"item\":\"https:\\\/\\\/mfwa.org\\\/our-partners-list\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Regroupement de la Presse Mauritanienne (RPM)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"name\":\"Media Foundation For West Africa\",\"description\":\"Promoting Freedom of Expression and Democracy in West Africa\",\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\",\"name\":\"Media Foundation for West Africa\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"width\":1683,\"height\":1113,\"caption\":\"Media Foundation for West Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/themfwa\",\"https:\\\/\\\/x.com\\\/TheMFWA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCF6HrPuXcV1K1Ed8AAq4Rdw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regroupement de la Presse Mauritanienne (RPM) - Media Foundation For West Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/","og_locale":"fr_FR","og_type":"article","og_title":"Regroupement de la Presse Mauritanienne (RPM) - Media Foundation For West Africa","og_description":"RPM est une association mauritanienne des professionnels des m\u00e9dias \u00a0qui a \u00e9t\u00e9 \u00a0cr\u00e9\u00e9e en 2005. Elle est compos\u00e9e&hellip;","og_url":"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/","og_site_name":"Media Foundation For West Africa","article_publisher":"https:\/\/www.facebook.com\/themfwa","article_modified_time":"2016-02-12T17:57:37+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/mfwa.org\/wp-content\/uploads\/2016\/02\/RPM_logo_arabic_fr_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TheMFWA","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/","url":"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/","name":"Regroupement de la Presse Mauritanienne (RPM) - Media Foundation For West Africa","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/#primaryimage"},"image":{"@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/#primaryimage"},"thumbnailUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2016\/02\/RPM_logo_arabic_fr_1.jpg","datePublished":"2016-02-08T14:23:45+00:00","dateModified":"2016-02-12T17:57:37+00:00","breadcrumb":{"@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/#primaryimage","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2016\/02\/RPM_logo_arabic_fr_1.jpg","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2016\/02\/RPM_logo_arabic_fr_1.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/mauritania-regroupement-de-la-presse-mauritanienne-rpm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mfwa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Our Partners","item":"https:\/\/mfwa.org\/our-partners-list\/"},{"@type":"ListItem","position":3,"name":"Regroupement de la Presse Mauritanienne (RPM)"}]},{"@type":"WebSite","@id":"https:\/\/mfwa.org\/fr\/#website","url":"https:\/\/mfwa.org\/fr\/","name":"Media Foundation For West Africa","description":"Promoting Freedom of Expression and Democracy in West Africa","publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mfwa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mfwa.org\/fr\/#organization","name":"Media Foundation for West Africa","url":"https:\/\/mfwa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","width":1683,"height":1113,"caption":"Media Foundation for West Africa"},"image":{"@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/themfwa","https:\/\/x.com\/TheMFWA","https:\/\/www.youtube.com\/channel\/UCF6HrPuXcV1K1Ed8AAq4Rdw"]}]}},"_links":{"self":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/our-partners-list\/5693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/our-partners-list"}],"about":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/types\/our-partners-list"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media\/5689"}],"wp:attachment":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media?parent=5693"}],"wp:term":[{"taxonomy":"partner-type","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/partner-type?post=5693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}