{"id":26279,"date":"2021-01-12T10:26:31","date_gmt":"2021-01-12T10:26:31","guid":{"rendered":"https:\/\/www.mfwa.org\/?post_type=our-partners-list&#038;p=26279"},"modified":"2022-09-09T16:18:54","modified_gmt":"2022-09-09T16:18:54","slug":"a-associacao-sindical-dos-jornalistas-de-cabo-verde","status":"publish","type":"our-partners-list","link":"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/","title":{"rendered":"A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde (AJOC)"},"content":{"rendered":"<div style=\"text-align: justify;\">A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde est une organisation \u00e0 but non lucratif form\u00e9e de professionnels de la presse, de la radio, de la t\u00e9l\u00e9vision, d\u2019agences de presse et de m\u00e9dias en ligne. Elle vise \u00e0 promouvoir l&#8217;int\u00e9gration sociale et professionnelle de tous les journalistes et individus. Fond\u00e9e le 24 novembre 1990, l&#8217;AJOC est ind\u00e9pendance vis-\u00e0-vis de l&#8217;Etat, des pouvoirs politiques et \u00e9conomiques, du gouvernement, des partis politiques, des \u00e9glises ou de tout autre groupe ou forme de pouvoir. Les activit\u00e9s de l\u2019AJOC, bas\u00e9e au Plateau dans la ville de Praia, s\u2019\u00e9tendent sur l&#8217;ensemble du territoire national.<\/div>\n","protected":false},"featured_media":26237,"template":"","partner-type":[302],"class_list":["post-26279","our-partners-list","type-our-partners-list","status-publish","has-post-thumbnail","hentry","partner-type-partenaires-nationaux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde (AJOC) - Media Foundation For West Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde (AJOC) - Media Foundation For West Africa\" \/>\n<meta property=\"og:description\" content=\"A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde est une organisation \u00e0 but non lucratif form\u00e9e de professionnels&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/\" \/>\n<meta property=\"og:site_name\" content=\"Media Foundation For West Africa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/themfwa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-09T16:18:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mfwa.org\/wp-content\/uploads\/2022\/09\/AJOC_LOGO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\\\/\",\"name\":\"A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde (AJOC) - Media Foundation For West Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/AJOC_LOGO.jpg\",\"datePublished\":\"2021-01-12T10:26:31+00:00\",\"dateModified\":\"2022-09-09T16:18:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/AJOC_LOGO.jpg\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/AJOC_LOGO.jpg\",\"width\":500,\"height\":532},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/our-partners-list\\\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our Partners\",\"item\":\"https:\\\/\\\/mfwa.org\\\/our-partners-list\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde (AJOC)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"name\":\"Media Foundation For West Africa\",\"description\":\"Promoting Freedom of Expression and Democracy in West Africa\",\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\",\"name\":\"Media Foundation for West Africa\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"width\":1683,\"height\":1113,\"caption\":\"Media Foundation for West Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/themfwa\",\"https:\\\/\\\/x.com\\\/TheMFWA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCF6HrPuXcV1K1Ed8AAq4Rdw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde (AJOC) - Media Foundation For West Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/","og_locale":"fr_FR","og_type":"article","og_title":"A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde (AJOC) - Media Foundation For West Africa","og_description":"A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde est une organisation \u00e0 but non lucratif form\u00e9e de professionnels&hellip;","og_url":"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/","og_site_name":"Media Foundation For West Africa","article_publisher":"https:\/\/www.facebook.com\/themfwa","article_modified_time":"2022-09-09T16:18:54+00:00","og_image":[{"width":500,"height":532,"url":"https:\/\/mfwa.org\/wp-content\/uploads\/2022\/09\/AJOC_LOGO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TheMFWA","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/","url":"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/","name":"A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde (AJOC) - Media Foundation For West Africa","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/#primaryimage"},"image":{"@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2022\/09\/AJOC_LOGO.jpg","datePublished":"2021-01-12T10:26:31+00:00","dateModified":"2022-09-09T16:18:54+00:00","breadcrumb":{"@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/#primaryimage","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2022\/09\/AJOC_LOGO.jpg","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2022\/09\/AJOC_LOGO.jpg","width":500,"height":532},{"@type":"BreadcrumbList","@id":"https:\/\/mfwa.org\/fr\/our-partners-list\/a-associacao-sindical-dos-jornalistas-de-cabo-verde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mfwa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Our Partners","item":"https:\/\/mfwa.org\/our-partners-list\/"},{"@type":"ListItem","position":3,"name":"A Associa\u00e7\u00e3o Sindical dos Jornalistas de Cabo Verde (AJOC)"}]},{"@type":"WebSite","@id":"https:\/\/mfwa.org\/fr\/#website","url":"https:\/\/mfwa.org\/fr\/","name":"Media Foundation For West Africa","description":"Promoting Freedom of Expression and Democracy in West Africa","publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mfwa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mfwa.org\/fr\/#organization","name":"Media Foundation for West Africa","url":"https:\/\/mfwa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","width":1683,"height":1113,"caption":"Media Foundation for West Africa"},"image":{"@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/themfwa","https:\/\/x.com\/TheMFWA","https:\/\/www.youtube.com\/channel\/UCF6HrPuXcV1K1Ed8AAq4Rdw"]}]}},"_links":{"self":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/our-partners-list\/26279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/our-partners-list"}],"about":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/types\/our-partners-list"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media\/26237"}],"wp:attachment":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media?parent=26279"}],"wp:term":[{"taxonomy":"partner-type","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/partner-type?post=26279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}