{"id":17670,"date":"2020-03-17T11:35:51","date_gmt":"2020-03-17T11:35:51","guid":{"rendered":"https:\/\/www.mfwa.org\/?post_type=issues-in-focus&#038;p=17670"},"modified":"2020-03-17T11:35:51","modified_gmt":"2020-03-17T11:35:51","slug":"deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook","status":"publish","type":"issues-in-focus","link":"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/","title":{"rendered":"Deux Journalistes Echoppent d&#8217;une Amende pour un Article sur la Corruption, Une Autre interrog\u00e9e sur un Post sur Facebook"},"content":{"rendered":"<p style=\"text-align: justify;\">Deux journalistes ont \u00e9t\u00e9 arr\u00eat\u00e9s, mis en accusation et condamn\u00e9s \u00e0 une amende de 5 millions de francs CFA (environ 8 600 dollars US) chacun pour une publication all\u00e9guant la corruption au plus haut niveau du gouvernement, tandis qu&#8217;une autre journaliste a \u00e9t\u00e9 convoqu\u00e9e et interrog\u00e9e pour un article publi\u00e9 sur Facebook.<\/p>\n<p style=\"text-align: justify;\">Le 3 mars 2020, le procureur de la R\u00e9publique de C\u00f4te d&#8217;Ivoire a ordonn\u00e9 l&#8217;arrestation de Yacouba Gbande, directeur et r\u00e9dacteur en chef du journal priv\u00e9 Le Temps, et de Barthelemy Tehin, \u00e9galement journaliste pour le m\u00eame journal apr\u00e8s la publication de l&#8217;article intitul\u00e9 &#8220;Fraude au sommet, corruption&#8221; : La C\u00f4te d&#8217;Ivoire, un v\u00e9ritable Etat voyou !&#8221;<\/p>\n<p style=\"text-align: justify;\">La brigade de recherche de la gendarmerie nationale a arr\u00eat\u00e9 les deux journalistes et les a interrog\u00e9s en rapport avec l&#8217;article, qui faisait \u00e9tat de divers actes de corruption de la part de hauts fonctionnaires du pays.<\/p>\n<p style=\"text-align: justify;\">Le m\u00eame jour, les journalistes ont \u00e9t\u00e9 traduits devant un tribunal d&#8217;Abidjan et condamn\u00e9s pour &#8220;atteinte \u00e0 l&#8217;honneur et au respect de plusieurs membres du gouvernement&#8221;. Ils ont \u00e9t\u00e9 condamn\u00e9s \u00e0 une amende de 5 millions de francs CFA (8 600 dollars US) chacun.<\/p>\n<p style=\"text-align: justify;\">De nombreux groupes de d\u00e9fense des droits de l&#8217;homme ont qualifi\u00e9 le proc\u00e8s rapide et son issue de scandaleux. L&#8217;avocat des deux journalistes, Claver N&#8217;dri, a d\u00e9clar\u00e9 que la rapidit\u00e9 du proc\u00e8s lui avait priv\u00e9 du temps n\u00e9cessaire pour \u00e9tudier le dossier, tandis que la direction du Temps a d\u00e9clar\u00e9 qu&#8217;elle ferait appel de la d\u00e9cision.<\/p>\n<p style=\"text-align: justify;\">C&#8217;\u00e9tait une &#8220;parodie de justice&#8221;, a protest\u00e9 Ousmane Sy Savane, directeur g\u00e9n\u00e9ral du groupe Cyclone, \u00e9diteur du Temps. &#8220;Nous allons faire appel de la d\u00e9cision&#8221;<\/p>\n<p style=\"text-align: justify;\">Le calvaire de Gbande et Tehin a \u00e9t\u00e9 la premi\u00e8re des deux violations enregistr\u00e9es en C\u00f4te d&#8217;Ivoire en l&#8217;espace de deux jours. Le 3 mars 2020, une journaliste travaillant pour la station de radio priv\u00e9e ATM \u00e0 Abidjan a \u00e9t\u00e9 convoqu\u00e9e et interrog\u00e9e par la police sur un post Facebook que les autorit\u00e9s ont qualifi\u00e9 de &#8220;faux&#8221;.<\/p>\n<p style=\"text-align: justify;\">Kacou Monique, qui est \u00e9galement la secr\u00e9taire g\u00e9n\u00e9rale de l&#8217;Union nationale des journalistes de C\u00f4te d&#8217;Ivoire (UNJCI), a affirm\u00e9 qu&#8217;il y avait un manque d&#8217;oxyg\u00e8ne \u00e0 l&#8217;h\u00f4pital de Port-Bou\u00ebt. Elle a ajout\u00e9 que le d\u00e9c\u00e8s r\u00e9cent de B\u00e9n\u00e9dicte Goumegou, une journaliste, dans cet \u00e9tablissement pourrait \u00eatre li\u00e9 \u00e0 cette p\u00e9nurie.<\/p>\n<p style=\"text-align: justify;\">Elle a \u00e9t\u00e9 convoqu\u00e9e le 5 mars 2020 par la police de Port-Bou\u00ebt, un quartier au sud d&#8217;Abidjan, et interrog\u00e9e pendant environ deux heures sur la publication qui, selon eux, pourrait provoquer une d\u00e9saffection pour l&#8217;h\u00f4pital et sa direction. Elle a ensuite \u00e9t\u00e9 lib\u00e9r\u00e9e avec une mise en garde pour \u00e9viter de publier de &#8220;fausses informations&#8221;.<\/p>\n<p style=\"text-align: justify;\">Le MFWA estime que le proc\u00e8s de Gbande et Tehin est h\u00e2tif et injustifi\u00e9. Le MFWA estime que le droit des responsables publics de prot\u00e9ger leur int\u00e9grit\u00e9 contre les attaques injustifi\u00e9es est contrebalanc\u00e9 par le devoir des m\u00e9dias d&#8217;examiner leurs actions et de signaler les manquements dans leur conduite ou leurs performances. S&#8217;\u00e9tant ouverts \u00e0 la critique en acceptant d&#8217;occuper une fonction publique, les responsables publics doivent, par cons\u00e9quent, \u00eatre plus tol\u00e9rants \u00e0 l&#8217;\u00e9gard du contr\u00f4le que les simples citoyens. C&#8217;est dans cette optique que nous trouvons que le proc\u00e8s pr\u00e9cipit\u00e9 des deux journalistes est une d\u00e9monstration d&#8217;intol\u00e9rance.<\/p>\n<p style=\"text-align: justify;\">La MFWA recommande des options de r\u00e8glement telles que le droit de r\u00e9ponse, les excuses et la r\u00e9tractation et le recours aux m\u00e9canismes de m\u00e9diation des organes nationaux de r\u00e9gulation des m\u00e9dias, en particulier pour les personnalit\u00e9s publiques offens\u00e9es par des publications sur le travail officiel.<\/p>\n<p style=\"text-align: justify;\">Nous f\u00e9licitons la direction du Temps d&#8217;avoir soutenu ses journalistes et nous soutenons pleinement sa d\u00e9cision de faire appel de la d\u00e9cision du tribunal.<\/p>\n<p style=\"text-align: justify;\">Nous consid\u00e9rons \u00e9galement la convocation et l&#8217;interrogatoire de Monique sur sa publication sur Facebook comme un acte d&#8217;intimidation. Les autorit\u00e9s de l&#8217;h\u00f4pital ont le droit de r\u00e9ponse aux affirmations de la journaliste concernant le manque d&#8217;oxyg\u00e8ne dans leur \u00e9tablissement. La police n&#8217;a pas \u00e0 se m\u00ealer de cette affaire.<\/p>\n","protected":false},"author":6,"featured_media":17566,"comment_status":"closed","ping_status":"closed","template":"","categories":[231],"tags":[],"country":[241],"class_list":["post-17670","issues-in-focus","type-issues-in-focus","status-publish","has-post-thumbnail","hentry","category-digital-rights-fr","country-cote-divoire-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deux Journalistes Echoppent d&#039;une Amende pour un Article sur la Corruption, Une Autre interrog\u00e9e sur un Post sur Facebook - Media Foundation For West Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deux Journalistes Echoppent d&#039;une Amende pour un Article sur la Corruption, Une Autre interrog\u00e9e sur un Post sur Facebook - Media Foundation For West Africa\" \/>\n<meta property=\"og:description\" content=\"Deux journalistes ont \u00e9t\u00e9 arr\u00eat\u00e9s, mis en accusation et condamn\u00e9s \u00e0 une amende de 5 millions de francs&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/\" \/>\n<meta property=\"og:site_name\" content=\"Media Foundation For West Africa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/themfwa\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mfwa.org\/wp-content\/uploads\/2020\/03\/cote.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\\\/\",\"name\":\"Deux Journalistes Echoppent d'une Amende pour un Article sur la Corruption, Une Autre interrog\u00e9e sur un Post sur Facebook - Media Foundation For West Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cote.jpg\",\"datePublished\":\"2020-03-17T11:35:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cote.jpg\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cote.jpg\",\"width\":900,\"height\":600,\"caption\":\"Yacouba Gbande and\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Issues in Focus\",\"item\":\"https:\\\/\\\/mfwa.org\\\/issues-in-focus\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Deux Journalistes Echoppent d&#8217;une Amende pour un Article sur la Corruption, Une Autre interrog\u00e9e sur un Post sur Facebook\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"name\":\"Media Foundation For West Africa\",\"description\":\"Promoting Freedom of Expression and Democracy in West Africa\",\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\",\"name\":\"Media Foundation for West Africa\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"width\":1683,\"height\":1113,\"caption\":\"Media Foundation for West Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/themfwa\",\"https:\\\/\\\/x.com\\\/TheMFWA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCF6HrPuXcV1K1Ed8AAq4Rdw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deux Journalistes Echoppent d'une Amende pour un Article sur la Corruption, Une Autre interrog\u00e9e sur un Post sur Facebook - Media Foundation For West Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/","og_locale":"fr_FR","og_type":"article","og_title":"Deux Journalistes Echoppent d'une Amende pour un Article sur la Corruption, Une Autre interrog\u00e9e sur un Post sur Facebook - Media Foundation For West Africa","og_description":"Deux journalistes ont \u00e9t\u00e9 arr\u00eat\u00e9s, mis en accusation et condamn\u00e9s \u00e0 une amende de 5 millions de francs&hellip;","og_url":"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/","og_site_name":"Media Foundation For West Africa","article_publisher":"https:\/\/www.facebook.com\/themfwa","og_image":[{"width":900,"height":600,"url":"https:\/\/mfwa.org\/wp-content\/uploads\/2020\/03\/cote.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TheMFWA","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/","url":"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/","name":"Deux Journalistes Echoppent d'une Amende pour un Article sur la Corruption, Une Autre interrog\u00e9e sur un Post sur Facebook - Media Foundation For West Africa","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/#primaryimage"},"image":{"@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/#primaryimage"},"thumbnailUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2020\/03\/cote.jpg","datePublished":"2020-03-17T11:35:51+00:00","breadcrumb":{"@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/#primaryimage","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2020\/03\/cote.jpg","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2020\/03\/cote.jpg","width":900,"height":600,"caption":"Yacouba Gbande and"},{"@type":"BreadcrumbList","@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/deux-journalistes-echoppent-dune-amende-pour-un-article-sur-la-corruption-une-autre-interrogee-sur-un-post-sur-facebook\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mfwa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Issues in Focus","item":"https:\/\/mfwa.org\/issues-in-focus\/"},{"@type":"ListItem","position":3,"name":"Deux Journalistes Echoppent d&#8217;une Amende pour un Article sur la Corruption, Une Autre interrog\u00e9e sur un Post sur Facebook"}]},{"@type":"WebSite","@id":"https:\/\/mfwa.org\/fr\/#website","url":"https:\/\/mfwa.org\/fr\/","name":"Media Foundation For West Africa","description":"Promoting Freedom of Expression and Democracy in West Africa","publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mfwa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mfwa.org\/fr\/#organization","name":"Media Foundation for West Africa","url":"https:\/\/mfwa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","width":1683,"height":1113,"caption":"Media Foundation for West Africa"},"image":{"@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/themfwa","https:\/\/x.com\/TheMFWA","https:\/\/www.youtube.com\/channel\/UCF6HrPuXcV1K1Ed8AAq4Rdw"]}]}},"_links":{"self":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/issues-in-focus\/17670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/issues-in-focus"}],"about":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/types\/issues-in-focus"}],"author":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/comments?post=17670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media\/17566"}],"wp:attachment":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media?parent=17670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/categories?post=17670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/tags?post=17670"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/country?post=17670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}