{"id":10273,"date":"2017-05-03T15:47:28","date_gmt":"2017-05-03T15:47:28","guid":{"rendered":"http:\/\/www.mfwa.org\/?post_type=issues-in-focus&#038;p=10273"},"modified":"2017-05-03T15:47:28","modified_gmt":"2017-05-03T15:47:28","slug":"mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression","status":"publish","type":"issues-in-focus","link":"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/","title":{"rendered":"MFWA se Joint \u00e0 IFEX pour P\u00e9titionner le Gouvernement de la Turquie sur la R\u00e9pression de la Libert\u00e9 d\u2019Expression"},"content":{"rendered":"<p style=\"text-align: justify;\">En l\u2019occasion de la Journ\u00e9e Mondiale de la Libert\u00e9 de la Presse (3Mai 2017), la Fondation des M\u00e9dias pour l\u2019Afrique de l\u2019Ouest(MFWA) se joint \u00e0 l\u2019IFEX, le r\u00e9seau mondial des organisations de la libert\u00e9 d\u2019expression et des droits de l\u2019Homme pour demander la lib\u00e9ration et la fin des poursuites des journalistes en Turquie.<\/p>\n<p style=\"text-align: justify;\">L\u2019appel est contenu dans une p\u00e9tition adress\u00e9e \u00e0 l\u2019Ambassadrice de la Turquie au Ghana\u00a0; Penbe Nesrin et ceci fait partie de la campagne des membres d\u2019IFEX pour demander la restauration des libert\u00e9s individuelles, de la presse et de la libert\u00e9 d\u2019expression en Turquie.<\/p>\n<p style=\"text-align: justify;\">\u00abDepuis la tentative de coup manqu\u00e9 de l\u2019ann\u00e9e pass\u00e9e, la Turquie est devenue le premier pays au monde \u00e0 emprisonner les journalistes avec pr\u00e8s de 150 journalistes qui ont \u00e9t\u00e9 arr\u00eat\u00e9s et dont la majorit\u00e9 est toujours en d\u00e9tention. Durant les mois apr\u00e8s le coup, plus de 180 organes des m\u00e9dias ont \u00e9t\u00e9 ferm\u00e9s, des milliers de personnes ont \u00e9t\u00e9 d\u00e9mis de leur emplois sur la base de leurs croyances ou associations\u00bb a not\u00e9 la p\u00e9tition.<\/p>\n<p style=\"text-align: justify;\">La MFWA exhorte la Turquie \u00e0 remplir ses obligations d\u2019apr\u00e8s les Conventions internationales et Europ\u00e9ennes des droits de l\u2019Homme sur le respect de la libert\u00e9 d\u2019expression.<\/p>\n<p style=\"text-align: justify;\">Les p\u00e9titionnaires ont exprim\u00e9s l\u2019espoir selon lequel un renouv\u00e8lement d\u2019engagement \u00e0 la libert\u00e9 d\u2019expression peut \u00eatre un d\u00e9but de la fin des poursuites des coll\u00e8gues d\u2019IFEX de l\u2019Initiative pour la Libert\u00e9 d\u2019Expression-Turquie et Bianet, y compris Sanar Yurdatapan et Erol \u00d6nderoglu.<\/p>\n<p style=\"text-align: justify;\">Veuillez lire la p\u00e9tition enti\u00e8re ci-dessous<\/p>\n<p style=\"text-align: justify;\"><strong>ATTN<\/strong>: Penbe\u00a0Nesrin,<\/p>\n<p style=\"text-align: justify;\">Ambassade de Turquie<\/p>\n<p style=\"text-align: justify;\">L8 Block 1 Section 17B<br \/>\nLabone Abafum Crescent<br \/>\nAccra<br \/>\nGhana<\/p>\n<p style=\"text-align: justify;\">3 Mai 2017<\/p>\n<p style=\"text-align: justify;\"><strong>Ambassadrice Penbe Nesrin,<\/strong><\/p>\n<p style=\"text-align: justify;\">La Fondation des M\u00e9dias pour l\u2019Afrique de l\u2019Ouest vous \u00e9crit \u00e0 l\u2019occasion de la Journ\u00e9e Mondiale de la Libert\u00e9 d\u2019Expression en tant que membre d\u2019IFEX, le r\u00e9seau mondial de 108 organisations d\u00e9di\u00e9es \u00e0 promouvoir et \u00e0 defender la libert\u00e9 d\u2019expression, pour vous appeler \u00e0 la restauration compl\u00e8te de la libert\u00e9 de personnes et de la libert\u00e9 d\u2019expression en Turquie<\/p>\n<p style=\"text-align: justify;\">Depuis la tentative de coup d\u2019\u00e9tat manqu\u00e9 de l\u2019ann\u00e9e pass\u00e9e, la Turquie est devenue le pays au monde qui envoie le plus de journalistes en prison, avec pr\u00e8s de 150 journalistes arr\u00eat\u00e9s, la majorit\u00e9 d\u2019entre eux est toujours en d\u00e9tention. Depuis des mois apr\u00e8s le coup, plus de 180 organes des m\u00e9dias ont \u00e9t\u00e9 ferm\u00e9s, des milliers de personnes ont \u00e9t\u00e9 licenci\u00e9s de leurs emplois sur la base de leurs croyances ou associations, et pour leurs connections suppos\u00e9es par les autorit\u00e9s de\u00a0l\u2019\u00e9tat avec \u00e9lecteurs du\u00a0\u00ab\u00a0Non\u00a0\u00bb pendant le referendum constitutionnel et les terroristes &#8211; tout cela a port\u00e9 de s\u00e9rieux coups aux espaces ouverts de dialogues en Turquie. Chaque Etat a le droit de prot\u00e9ger ses citoyens des pr\u00e9judices, mais ces actions sont all\u00e9s au-del\u00e0 des demandes de la protection publique, et sont en train de porter un v\u00e9ritable coup \u00e0 la culture politique vibrante qui distingue une d\u00e9mocratie de la dictature.<\/p>\n<p style=\"text-align: justify;\">Plus qu\u2019une simple exag\u00e9ration, les pouvoirs d\u00e9cr\u00e9t\u00e9s par l\u2019\u00e9tat d\u2019urgence semblent devenir une couverture d\u2019instruments de r\u00e9pression des voix dissidentes. L\u2019extension de la r\u00e9pression aux Kurdes, Alevi et les m\u00e9dias de la gauche non impliqu\u00e9s dans le coup sugg\u00e8re que le d\u00e9cret r\u00e9cemment renouvel\u00e9 a \u00e9t\u00e9 abus\u00e9 au-del\u00e0 des objectifs fix\u00e9s pour r\u00e9primer des personnes et des groupes qui sont simplement g\u00eanants pour le gouvernement au pouvoir, mais qui ne repr\u00e9sentent pas de menaces au syst\u00e8me d\u00e9mocratique. De nombreuses personnes ont \u00e9t\u00e9 d\u00e9tenues et punies du fait de leurs d\u00e9saccords avec les actions ou les politiques du gouvernement \u00e9lus, ou font partie de ou sont sympathisants d\u2019un groupe minoritaire. En adoptant cette approche, la Turquie est en train de violer les principes de justice des droits humains internationalement reconnus et universellement accept\u00e9s-de ce fait attribue la culpabilit\u00e9 par association, non sur la base d\u2019\u00e9vidence, et punit des personnes pour leurs pens\u00e9es et croyances, et non pour leurs actes.<\/p>\n<p style=\"text-align: justify;\">Nous croyons que ces abus de l\u2019\u00e9tat d\u2019urgence d\u00e9cr\u00e9t\u00e9 doivent prendre fin. Nous appelons le gouvernement \u00e0 suspendre toutes les poursuites en cours dans les tribunaux de la Turquie qui ne r\u00e9pondent pas aux exigences des standards internationaux des libert\u00e9s d\u2019expression, et de fixer de nouvelles limites aux pouvoirs accord\u00e9s \u00e0 l\u2019\u00e9tat d\u2019urgence en vue du respect des obligations de la Turquie selon les conventions internationales et europ\u00e9ennes sur les droits de l\u2019Homme.<\/p>\n<p style=\"text-align: justify;\">Nous esp\u00e9rons que le renouvellement de l\u2019engagement pour la libert\u00e9 d\u2019expression peut commencer avec la fin des poursuites de nos coll\u00e8gues \u00e0 l\u2019Initiative pour la Libert\u00e9 d\u2019Expression-Turquie et Bianet, y compris Sanar Yurdatapan et Erol \u00d6nderoglu, et de tous ceux qui ont \u00e9t\u00e9 avec eux durant la campagne de solidarit\u00e9 au r\u00e9dacteur \u00d6zg\u00fcr G\u00fcndem invit\u00e9 l\u2019ann\u00e9e pass\u00e9e. Nous lan\u00e7ons aussi l\u2019appel pour l\u2019annulation des peines de condamnation de l\u2019enseignante Ay\u015fe \u00c7elik, punie pour des d\u00e9clarations de d\u00e9nonciation du silence \u00e0 propos des tueries en cours dans le Diyarbakir, et avec qui de nombreuse personnes sont devenues des \u2018\u2019co-signataires\u2019\u2019 symboliques de sa d\u00e9claration, y compris Sanar.<\/p>\n<p style=\"text-align: justify;\">Madame l\u2019Ambassadrice, les actes tels que ceux d\u2019Ay\u015fe et de nos coll\u00e8gues ne sont pas des actes de terrorismes &#8211; c\u2019est plut\u00f4t des actes de libert\u00e9 d\u2019expression. Etant donn\u00e9 que l\u2019extr\u00e9misme politique et l\u2019intol\u00e9rance gagnent du terrain dans le monde entier, le r\u00f4le d\u2019une soci\u00e9t\u00e9 civile saine et active de la libert\u00e9 de la presse n\u2019a jamais \u00e9t\u00e9 aussi important. C\u2019est \u00e0 travers leur r\u00f4le de promotion de d\u00e9bat contradictoire mais pacifique \u00e0 propos de tel sujet que la d\u00e9mocratie survit et prosp\u00e8re.<\/p>\n<p style=\"text-align: justify;\">En reconnaissance des deux obligations du trait\u00e9 du gouvernement de la Turquie et la contribution vitale de la presse et des groups de la soci\u00e9t\u00e9 civile en Turquie, nous appelons le gouvernement \u00e0:<\/p>\n<ol style=\"text-align: justify;\">\n<li>Ramener la d\u00e9tention de la police sans examen juridique \u00e0 la p\u00e9riode normale de quatre jours maximum, et que l\u2019amende et les dispositions de l\u2019\u00e9tat d\u2019urgence soit compatibles avec la Convention Europ\u00e9enne sur les Droits de l\u2019Homme et le Pacte International Relatifs aux Droits Civils et Politiques<\/li>\n<li>Limiter clairement les charges de terrorisme contre les personnes pour qui: l\u2019\u00e9vidence des actes de violence existent clairement, o\u00f9 l\u2019intention de commettre des actes de violence est \u00e9tablie, ou qui pr\u00f4nent des actes de violence, et retirer les charges de terrorisme contre tous ce qui n\u2019ont pas commis de tels actes.<\/li>\n<li>R\u00e9f\u00e9rer les cas des organes de m\u00e9dias affect\u00e9s par les r\u00e9centes fermetures \u00e0 la justice, et leur permettre d\u2019op\u00e9rer au moins et ce jusqu\u2019\u00e0 ce qu\u2019ils ne soient trouv\u00e9s coupables d\u2019un crime s\u00e9rieux.<\/li>\n<li>Renouveler le respect de l\u2019accr\u00e9ditation de la presse par les agents de l\u2019\u00e9tat, et retourner les accr\u00e9ditations confisqu\u00e9es \u00e0 la presse non coupables d\u2019aucun crime.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Dans l\u2019attende de votre r\u00e9ponse.<\/p>\n<p style=\"text-align: justify;\">Sign\u00e9<\/p>\n<p style=\"text-align: justify;\">Fondation des M\u00e9dias pour l\u2019Afrique de l\u2019Ouest<\/p>\n","protected":false},"author":2,"featured_media":10213,"comment_status":"closed","ping_status":"closed","template":"","categories":[149],"tags":[],"country":[],"class_list":["post-10273","issues-in-focus","type-issues-in-focus","status-publish","has-post-thumbnail","hentry","category-free-expression-violations"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MFWA se Joint \u00e0 IFEX pour P\u00e9titionner le Gouvernement de la Turquie sur la R\u00e9pression de la Libert\u00e9 d\u2019Expression - Media Foundation For West Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MFWA se Joint \u00e0 IFEX pour P\u00e9titionner le Gouvernement de la Turquie sur la R\u00e9pression de la Libert\u00e9 d\u2019Expression - Media Foundation For West Africa\" \/>\n<meta property=\"og:description\" content=\"En l\u2019occasion de la Journ\u00e9e Mondiale de la Libert\u00e9 de la Presse (3Mai 2017), la Fondation des M\u00e9dias&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/\" \/>\n<meta property=\"og:site_name\" content=\"Media Foundation For West Africa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/themfwa\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/erdogan-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\\\/\",\"name\":\"MFWA se Joint \u00e0 IFEX pour P\u00e9titionner le Gouvernement de la Turquie sur la R\u00e9pression de la Libert\u00e9 d\u2019Expression - Media Foundation For West Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/erdogan-1.jpg\",\"datePublished\":\"2017-05-03T15:47:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/erdogan-1.jpg\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/erdogan-1.jpg\",\"width\":600,\"height\":400,\"caption\":\"Photo credit: warfiles.ru\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/issues-in-focus\\\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Issues in Focus\",\"item\":\"https:\\\/\\\/mfwa.org\\\/issues-in-focus\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MFWA se Joint \u00e0 IFEX pour P\u00e9titionner le Gouvernement de la Turquie sur la R\u00e9pression de la Libert\u00e9 d\u2019Expression\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"name\":\"Media Foundation For West Africa\",\"description\":\"Promoting Freedom of Expression and Democracy in West Africa\",\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\",\"name\":\"Media Foundation for West Africa\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"width\":1683,\"height\":1113,\"caption\":\"Media Foundation for West Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/themfwa\",\"https:\\\/\\\/x.com\\\/TheMFWA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCF6HrPuXcV1K1Ed8AAq4Rdw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MFWA se Joint \u00e0 IFEX pour P\u00e9titionner le Gouvernement de la Turquie sur la R\u00e9pression de la Libert\u00e9 d\u2019Expression - Media Foundation For West Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/","og_locale":"fr_FR","og_type":"article","og_title":"MFWA se Joint \u00e0 IFEX pour P\u00e9titionner le Gouvernement de la Turquie sur la R\u00e9pression de la Libert\u00e9 d\u2019Expression - Media Foundation For West Africa","og_description":"En l\u2019occasion de la Journ\u00e9e Mondiale de la Libert\u00e9 de la Presse (3Mai 2017), la Fondation des M\u00e9dias&hellip;","og_url":"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/","og_site_name":"Media Foundation For West Africa","article_publisher":"https:\/\/www.facebook.com\/themfwa","og_image":[{"width":600,"height":400,"url":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/erdogan-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TheMFWA","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/","url":"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/","name":"MFWA se Joint \u00e0 IFEX pour P\u00e9titionner le Gouvernement de la Turquie sur la R\u00e9pression de la Libert\u00e9 d\u2019Expression - Media Foundation For West Africa","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/#primaryimage"},"image":{"@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/#primaryimage"},"thumbnailUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/erdogan-1.jpg","datePublished":"2017-05-03T15:47:28+00:00","breadcrumb":{"@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/#primaryimage","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/erdogan-1.jpg","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/erdogan-1.jpg","width":600,"height":400,"caption":"Photo credit: warfiles.ru"},{"@type":"BreadcrumbList","@id":"https:\/\/mfwa.org\/fr\/issues-in-focus\/mfwa-se-joint-a-ifex-pour-petitionner-le-gouvernement-de-la-turquie-sur-la-repression-de-la-liberte-dexpression\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mfwa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Issues in Focus","item":"https:\/\/mfwa.org\/issues-in-focus\/"},{"@type":"ListItem","position":3,"name":"MFWA se Joint \u00e0 IFEX pour P\u00e9titionner le Gouvernement de la Turquie sur la R\u00e9pression de la Libert\u00e9 d\u2019Expression"}]},{"@type":"WebSite","@id":"https:\/\/mfwa.org\/fr\/#website","url":"https:\/\/mfwa.org\/fr\/","name":"Media Foundation For West Africa","description":"Promoting Freedom of Expression and Democracy in West Africa","publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mfwa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mfwa.org\/fr\/#organization","name":"Media Foundation for West Africa","url":"https:\/\/mfwa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","width":1683,"height":1113,"caption":"Media Foundation for West Africa"},"image":{"@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/themfwa","https:\/\/x.com\/TheMFWA","https:\/\/www.youtube.com\/channel\/UCF6HrPuXcV1K1Ed8AAq4Rdw"]}]}},"_links":{"self":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/issues-in-focus\/10273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/issues-in-focus"}],"about":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/types\/issues-in-focus"}],"author":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/comments?post=10273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media\/10213"}],"wp:attachment":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media?parent=10273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/categories?post=10273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/tags?post=10273"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/country?post=10273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}