{"id":10265,"date":"2017-05-11T13:04:36","date_gmt":"2017-05-11T13:04:36","guid":{"rendered":"http:\/\/www.mfwa.org\/?post_type=country-highlights&#038;p=10265"},"modified":"2017-05-23T13:08:18","modified_gmt":"2017-05-23T13:08:18","slug":"la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse","status":"publish","type":"country-highlights","link":"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/","title":{"rendered":"La Libert\u00e9 des\u00a0Medias Menac\u00e9e par le Vote Pr\u00e9vu d\u2019une Loi R\u00e9pressive de la Presse"},"content":{"rendered":"<p style=\"text-align: justify;\">Le 5 Mai 2017, le gouvernement de la Cote d\u2019Ivoire a pr\u00e9sent\u00e9 un nouveau projet de loi sur la presse qui contient des dispositions r\u00e9pressives sur les d\u00e9lits de presse devant l\u2019Assembl\u00e9e Nationale du pays. La pr\u00e9sentation du projet de loi a donn\u00e9 lieu \u00e0 des protestations spontan\u00e9es et des condamnations de la part de la communaut\u00e9 de la presse et des organisations de la d\u00e9fense de la libert\u00e9 d\u2019expression dans le pays.<\/p>\n<p style=\"text-align: justify;\">Le 3 Mai 2017, lors de la c\u00e9l\u00e9bration mondiale de la journ\u00e9e de la libert\u00e9 de la presse, les membres des organes de presse et des organisations de plaidoyer de la libert\u00e9 d\u2019expression ont manifest\u00e9 pour d\u00e9noncer l\u2019imminente pr\u00e9sentation de la loi controvers\u00e9e. Ce nouveau projet de loi est consid\u00e9r\u00e9 comme une r\u00e9gression majeure par rapport aux acquis r\u00e9alis\u00e9s par rapport \u00e0 la libert\u00e9 d\u2019expression ainsi que les processus d\u00e9mocratiques post-conflit en cours.<\/p>\n<figure id=\"attachment_10186\" aria-describedby=\"caption-attachment-10186\" style=\"width: 379px\" class=\"wp-caption alignright\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-10186\" src=\"http:\/\/www.mfwa.org\/wp-content\/uploads\/2017\/05\/CDI-media-procession-copy-1-600x400.jpg\" alt=\"\" width=\"379\" height=\"252\" srcset=\"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/CDI-media-procession-copy-1-600x400.jpg 600w, https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/CDI-media-procession-copy-1-270x180.jpg 270w, https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/CDI-media-procession-copy-1-570x380.jpg 570w, https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/CDI-media-procession-copy-1.jpg 720w, https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/CDI-media-procession-copy-1-370x247.jpg 370w, https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/CDI-media-procession-copy-1-375x250.jpg 375w\" sizes=\"(max-width: 600px) 100vw, 379px\" \/><figcaption id=\"caption-attachment-10186\" class=\"wp-caption-text\">Marche de Protestation du 3 Mai des m\u00e9dias sur le projet de loi<br \/>Photo cr\u00e9dit: lepointsur.com<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Des sections de ce nouveau projet de loi prescrivent des termes d\u2019emprisonnement allant jusqu\u2019\u00e0 trois ans pour certaines d\u00e9lits par voie de presse. La proposition de loi, si elle est vot\u00e9e, imposera \u00e9galement des amendes allant jusqu\u2019\u00e0\u00a0 3,000,000 Francs CFA (\u00e9quivalent \u00e0 US$4,988 ) pour d\u2019autres d\u00e9lits. Dans un pays o\u00f9 la libert\u00e9 de presse fait face d\u00e9j\u00e0 \u00e0 de nombreux d\u00e9fis juridiques et \u00e0 des restrictions non-l\u00e9gales, le projet de loi, si elle est vot\u00e9e, pourrait avoir davantage un effet n\u00e9faste sur les m\u00e9dias.<\/p>\n<p style=\"text-align: justify;\">Une disposition du nouveau projet de loi consid\u00e9r\u00e9e comme tr\u00e8s large stipule comme suit que toute personne:\u00a0<em>\u00abest puni d\u2019un emprisonnement d\u2019un \u00e0 cinq ans et d\u2019une amende de 300,000 \u00e0 3,000,000 de francs, quiconque par voie de presse ou par tout autre moyen de publication: incite au vol et au pillage, au meurtre, \u00e0 l\u2019incendie et \u00e0 la destruction par quelque moyen que ce soit, de biens publics et priv\u00e9s, \u00e0 toutes formes de violences exerc\u00e9es \u00e0 l\u2019encontre de personnes physiques et morales ainsi que sur les biens, ou \u00e0 l\u2019apologie des m\u00eames crimes et d\u00e9lits ; incite \u00e0 la x\u00e9nophobie, \u00e0 la haine religieuse, \u00e0 la haine raciale et \u00e0 la haine sous toutes ses formes ; fait l\u2019apologie des crimes de guerre, des crimes contre l\u2019humanit\u00e9, des crimes de g\u00e9nocides ou de collaborations avec l\u2019ennemi ; incite les militaires et des forces de l\u2019ordre \u00e0 l\u2019insoumission et \u00e0 la r\u00e9bellion ; porte atteinte \u00e0 l\u2019int\u00e9grit\u00e9 du territoire national, \u00e0 la s\u00fbret\u00e9 int\u00e9rieure et ext\u00e9rieure de l\u2019Etat\u00bb.<\/em><\/p>\n<p style=\"text-align: justify;\">Tandis qu\u2019il apparait logique que toute personne, y compris les journalistes, qui commettent l\u2019une de ces infractions ci-dessus mentionn\u00e9es doit r\u00e9pondre de son acte, la disposition ci-dessus est sujette \u00e0 de larges interpr\u00e9tations subjectives et peut \u00eatre exploit\u00e9e par des politiciens et des personnes influentes pour r\u00e9gler des comptes \u00e0 des journalistes critiques. Ceci en retour, a le potentiel de contraindre les m\u00e9dias \u00e0 l\u2019autocensure.<\/p>\n<p style=\"text-align: justify;\">De surcroit, les articles 174 et 175 du Code P\u00e9nal Ivoirien prennent ad\u00e9quatement en question de telles infractions. Un\u00a0 nouveau projet de loi visant particuli\u00e8rement les m\u00e9dias est donc tr\u00e8s alarmant \u00e9tant donn\u00e9 que cela sugg\u00e8re une nouvelle volont\u00e9 des autorit\u00e9s d\u2019\u00a0\u00aben d\u00e9coudre avec\u00bb les m\u00e9dias.<\/p>\n<p style=\"text-align: justify;\">La disposition de ce nouveau projet de lois pour la presse est particuli\u00e8rement inqui\u00e9tante \u00e9tant donn\u00e9 que cela vise \u00e0 remplacer la loi de la presse existante de 2004, qui stipule sans \u00e9quivoque que les d\u00e9lits de presse ne doivent pas donner lieu \u00e0 de l\u2019emprisonnement.<\/p>\n<p style=\"text-align: justify;\">\u00abCette loi, nous nous en m\u00e9fions. En tout cas, il y a quelques articles qui nous d\u00e9rangent \u00bb, a fait savoir Moussa Traore, le pr\u00e9sident de l\u2019Union Nationale des Journalistes de la Cote d\u2019Ivoire (UNJCI).<\/p>\n<p style=\"text-align: justify;\">La MFWA est pr\u00e9occup\u00e9e \u00e0 propos du vote pr\u00e9vu de la loi r\u00e9pressive.\u00a0\u00abLes m\u00e9dias ivoiriens font face d\u00e9j\u00e0 \u00e0 de nombreuses formes de r\u00e9pressions y compris la suspension fr\u00e9quente des organes des m\u00e9dias par l\u2019autorit\u00e9 de r\u00e9gulation de la presse et les attaques sur les journalistes\u00bb a dit Sulemana Braimah, Directeur Ex\u00e9cutif de MFWA.<\/p>\n<p style=\"text-align: justify;\">La loi en perspective est une autre l\u00e9gislation qui paralysera davantage les m\u00e9dias dans le pays et cela n\u2019augure rien de bon pour la reconstruction post-conflit en cours et la consolidation des processus d\u00e9mocratique en C\u00f4te d\u2019Ivoire. La MFWA exhorte donc les autorit\u00e9s Ivoirien \u00e0 retirer du projet de loi, la disposition qui criminalise les m\u00e9dias et les d\u00e9lits de presse. La MFWA exhorte aussi la communaut\u00e9 des m\u00e9dias et les autres acteurs\u00a0 \u00e0 faire pr\u00e9valoir la n\u00e9cessit\u00e9 de l\u2019am\u00e9lioration de la libert\u00e9 de la presse et des m\u00e9dias aux autorit\u00e9s dans le pays plut\u00f4t que l\u2019adoption des mesures qui restreignent davantage l\u2019environnement des m\u00e9dias d\u00e9j\u00e0 r\u00e9prim\u00e9.<\/p>\n","protected":false},"author":2,"featured_media":10220,"comment_status":"closed","ping_status":"closed","template":"","categories":[320],"country":[241],"class_list":["post-10265","country-highlights","type-country-highlights","status-publish","has-post-thumbnail","hentry","category-la-liberte-dexpression","country-cote-divoire-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Libert\u00e9 des\u00a0Medias Menac\u00e9e par le Vote Pr\u00e9vu d\u2019une Loi R\u00e9pressive de la Presse - Media Foundation For West Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Libert\u00e9 des\u00a0Medias Menac\u00e9e par le Vote Pr\u00e9vu d\u2019une Loi R\u00e9pressive de la Presse - Media Foundation For West Africa\" \/>\n<meta property=\"og:description\" content=\"Le 5 Mai 2017, le gouvernement de la Cote d\u2019Ivoire a pr\u00e9sent\u00e9 un nouveau projet de loi sur&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/\" \/>\n<meta property=\"og:site_name\" content=\"Media Foundation For West Africa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/themfwa\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-23T13:08:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/Ouattaraa-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TheMFWA\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/country-highlights\\\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/country-highlights\\\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\\\/\",\"name\":\"La Libert\u00e9 des\u00a0Medias Menac\u00e9e par le Vote Pr\u00e9vu d\u2019une Loi R\u00e9pressive de la Presse - Media Foundation For West Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/country-highlights\\\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/country-highlights\\\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Ouattaraa-1.jpg\",\"datePublished\":\"2017-05-11T13:04:36+00:00\",\"dateModified\":\"2017-05-23T13:08:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/country-highlights\\\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mfwa.org\\\/fr\\\/country-highlights\\\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/country-highlights\\\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Ouattaraa-1.jpg\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Ouattaraa-1.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Pr\u00e9sident de la C\u00f4te d\u2019Ivoire, Alassane Ouattara\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/country-highlights\\\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Country Highlights\",\"item\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/country-highlights\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Libert\u00e9 des\u00a0Medias Menac\u00e9e par le Vote Pr\u00e9vu d\u2019une Loi R\u00e9pressive de la Presse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"name\":\"Media Foundation For West Africa\",\"description\":\"Promoting Freedom of Expression and Democracy in West Africa\",\"publisher\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#organization\",\"name\":\"Media Foundation for West Africa\",\"url\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/mfwa.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/mfwa-logo-01.png\",\"width\":1683,\"height\":1113,\"caption\":\"Media Foundation for West Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/mfwa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/themfwa\",\"https:\\\/\\\/x.com\\\/TheMFWA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCF6HrPuXcV1K1Ed8AAq4Rdw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Libert\u00e9 des\u00a0Medias Menac\u00e9e par le Vote Pr\u00e9vu d\u2019une Loi R\u00e9pressive de la Presse - Media Foundation For West Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/","og_locale":"fr_FR","og_type":"article","og_title":"La Libert\u00e9 des\u00a0Medias Menac\u00e9e par le Vote Pr\u00e9vu d\u2019une Loi R\u00e9pressive de la Presse - Media Foundation For West Africa","og_description":"Le 5 Mai 2017, le gouvernement de la Cote d\u2019Ivoire a pr\u00e9sent\u00e9 un nouveau projet de loi sur&hellip;","og_url":"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/","og_site_name":"Media Foundation For West Africa","article_publisher":"https:\/\/www.facebook.com\/themfwa","article_modified_time":"2017-05-23T13:08:18+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/Ouattaraa-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TheMFWA","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/","url":"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/","name":"La Libert\u00e9 des\u00a0Medias Menac\u00e9e par le Vote Pr\u00e9vu d\u2019une Loi R\u00e9pressive de la Presse - Media Foundation For West Africa","isPartOf":{"@id":"https:\/\/mfwa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/#primaryimage"},"image":{"@id":"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/#primaryimage"},"thumbnailUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/Ouattaraa-1.jpg","datePublished":"2017-05-11T13:04:36+00:00","dateModified":"2017-05-23T13:08:18+00:00","breadcrumb":{"@id":"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/#primaryimage","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/Ouattaraa-1.jpg","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2017\/05\/Ouattaraa-1.jpg","width":1024,"height":683,"caption":"Pr\u00e9sident de la C\u00f4te d\u2019Ivoire, Alassane Ouattara"},{"@type":"BreadcrumbList","@id":"https:\/\/mfwa.org\/fr\/country-highlights\/la-liberte-des-medias-menacee-par-le-vote-prevu-dune-loi-repressive-de-la-presse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mfwa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Country Highlights","item":"https:\/\/mfwa.org\/fr\/country-highlights\/"},{"@type":"ListItem","position":3,"name":"La Libert\u00e9 des\u00a0Medias Menac\u00e9e par le Vote Pr\u00e9vu d\u2019une Loi R\u00e9pressive de la Presse"}]},{"@type":"WebSite","@id":"https:\/\/mfwa.org\/fr\/#website","url":"https:\/\/mfwa.org\/fr\/","name":"Media Foundation For West Africa","description":"Promoting Freedom of Expression and Democracy in West Africa","publisher":{"@id":"https:\/\/mfwa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mfwa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mfwa.org\/fr\/#organization","name":"Media Foundation for West Africa","url":"https:\/\/mfwa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","contentUrl":"https:\/\/mfwa.org\/wp-content\/uploads\/2024\/01\/mfwa-logo-01.png","width":1683,"height":1113,"caption":"Media Foundation for West Africa"},"image":{"@id":"https:\/\/mfwa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/themfwa","https:\/\/x.com\/TheMFWA","https:\/\/www.youtube.com\/channel\/UCF6HrPuXcV1K1Ed8AAq4Rdw"]}]}},"_links":{"self":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/country-highlights\/10265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/country-highlights"}],"about":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/types\/country-highlights"}],"author":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/comments?post=10265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media\/10220"}],"wp:attachment":[{"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/media?parent=10265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/categories?post=10265"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/mfwa.org\/fr\/wp-json\/wp\/v2\/country?post=10265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}